{"id":6917,"count":1,"description":"","link":"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/","name":"valenecia","slug":"valenecia","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>valenecia Archive - Club Villamar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"valenecia Archive - Club Villamar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/\" \/>\n<meta property=\"og:site_name\" content=\"Club Villamar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/\",\"url\":\"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/\",\"name\":\"valenecia Archive - Club Villamar\",\"isPartOf\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.clubvillamar.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"valenecia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#website\",\"url\":\"https:\/\/www.clubvillamar.de\/blog\/\",\"name\":\"Club Villamar\",\"description\":\"Relax poolside at your private Spanish villa\",\"publisher\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.clubvillamar.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#organization\",\"name\":\"Club Villamar\",\"url\":\"https:\/\/www.clubvillamar.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg\",\"contentUrl\":\"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Club Villamar\"},\"image\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"valenecia Archive - Club Villamar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/","og_locale":"de_DE","og_type":"article","og_title":"valenecia Archive - Club Villamar","og_url":"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/","og_site_name":"Club Villamar","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/","url":"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/","name":"valenecia Archive - Club Villamar","isPartOf":{"@id":"https:\/\/www.clubvillamar.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.clubvillamar.de\/blog\/tag\/valenecia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.clubvillamar.de\/blog\/"},{"@type":"ListItem","position":2,"name":"valenecia"}]},{"@type":"WebSite","@id":"https:\/\/www.clubvillamar.de\/blog\/#website","url":"https:\/\/www.clubvillamar.de\/blog\/","name":"Club Villamar","description":"Relax poolside at your private Spanish villa","publisher":{"@id":"https:\/\/www.clubvillamar.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clubvillamar.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.clubvillamar.de\/blog\/#organization","name":"Club Villamar","url":"https:\/\/www.clubvillamar.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg","contentUrl":"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg","width":1000,"height":1000,"caption":"Club Villamar"},"image":{"@id":"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/tags\/6917"}],"collection":[{"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/posts?tags=6917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}