{"id":20128,"date":"2018-02-23T23:38:30","date_gmt":"2018-02-23T23:38:30","guid":{"rendered":"https:\/\/www.clubvillamar.de\/blog\/?p=20128"},"modified":"2018-03-19T10:56:01","modified_gmt":"2018-03-19T10:56:01","slug":"kalender-der-feste-und-feiertage-in-lloret-de-mar","status":"publish","type":"post","link":"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/","title":{"rendered":"Kalender der Feste und Feiertage in Lloret de Mar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-46115 size-full\" src=\"https:\/\/www.clubvillamar.com\/blog\/wp-content\/uploads\/2018\/01\/shutterstock_494682451.jpg\" alt=\"\" width=\"1920\" height=\"1080\" \/><\/p>\n<p><strong>Sie fahren im Urlaub nach Lloret de Mar? Ihr Aufenthalt k\u00f6nnte mit einem der z<\/strong><strong>ahlreichen Feste Kataloniens zusammenfallen! <\/strong><strong><br \/>\n<\/strong><\/p>\n<p><strong>Eine sch\u00f6ne Gelegeneheit, die festliche Atmosph\u00e4re zu genie\u00dfen.<\/strong><strong><br \/>\n<\/strong><\/p>\n<h2>Die Feiertage in Katalonien<\/h2>\n<p>In Spanien gibt es zwei Arten von Feiertagen: <strong>nationale Feiertage<\/strong>, welche im ganzen Land dieselben sind, wie der 1. Mai (Tag der Arbeit) oder der 12. Oktober (spanischer Nationaltag, auch \u201ed\u00eda de la Hispanidad\u201d genannt); und katalanische<strong> Feiertage<\/strong>, die auch in <strong>Lloret de Mar<\/strong> gefeiert werden. Einige Feste werden nur in einzelnen St\u00e4dten gefeiert, wie zum Beispiel Barcelona.<\/p>\n<p>Schauen Sie sich den Feiertagskalender f\u00fcr 2018 an und bereiten Sie Ihren Urlaub noch besser vor.<\/p>\n<h2>Die Hauptfeste in Lloret de Mar<\/h2>\n<p>Das ganze Jahr \u00fcber gibt es verschiedene Feste, die zahlreiche Aspekte im <strong>Le<\/strong><strong>ben von Lloret de Mar<\/strong> ausmachen. Wir haben die wichtigsten Ereignisse ausgew\u00e4hlt. Eine echte Chance f\u00fcr Urlauber, am Leben der Stadt teilzunehmen und die <strong>katalanische Kultur zu endecken.<\/strong><\/p>\n<p><strong>Sant Jordi <\/strong>(St-Georgs-Tag) wird jedes Jahr am 23. April gefeiert, fast so ein wenig wie ein kleiner katalanischer Valentinstag. Das ist traditionell die Gelegenheit, einer geliebten Person eine Rose zu schenken. Nat\u00fcrlich ist es fast ein Muss, dass die Rose die Farben der katalanischen Flagge hat!<\/p>\n<p><strong>Johannisnacht<\/strong> (oder Sant Joan auf katalanisch) wird jedes Jahr in der Nacht vom 23. auf den 24. Juni gefeiert. Dieses Fest leitet den Sommer ein (Sommersonnenwende). Zu dieser Gelegenheit k\u00f6nnen Sie den vielen <strong>Feuerwerksshows <\/strong>beiwohnen. Die Spanier nutzen die Gelegenheit dieses Festes, Feuerwerk in den Stra\u00dfen loszulassen. Die Johannisnacht endet mit dem Genuss von Coca, einem typisch katalanischen Kuchen und Cava (Sekt).<\/p>\n<p>Sollten Sie zwischen 23. und 30. Juni in Lloret de Mar sein, dann k\u00f6nnen Sie von dem <strong>Feuerwerkswettbewerb in <\/strong><a href=\"#LP_9\" target=\"_blank\" rel=\"noopener\">Blanes<\/a> (einem Nachbardorf von Lloret de Mar) profitieren. Es ist eine spektakul\u00e4re Show in einer atemberaubenden nat\u00fcrlichen Umgebung. Um eine gute Sicht zu haben, raten wir Ihnen, fr\u00fch (vor 22 Uhr) am <strong>Strand von<\/strong> <strong>Blanes <\/strong>zu sein. Der Wettbewerb ist so ber\u00fchmt, dass jedes Jahr Tausende von Menschen in Blanes zusammen kommen, um daran teilzuhaben. Dies ist definitiv eine der <strong>besten Feuerwerkshows in ganz Spanien<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-42370 size-full\" src=\"https:\/\/www.clubvillamar.com\/blog\/wp-content\/uploads\/2018\/01\/182-Lloret-de-Mar-Blanes-Fireworks-Festival.jpg\" alt=\"\" width=\"1200\" height=\"627\" \/><\/p>\n<p><strong>Ferieng\u00e4ste in Lloret de Mar <\/strong>k\u00f6nnen am 24. Juli <strong>Santa Cristina<\/strong> mitfeiern. Dies ist das Stadtfest , denn Santa Cristina ist die <strong>Schutzpatronin von Lloret de Mar<\/strong>. Sie k\u00f6nnen die Prozession anschauen, welche zur gleichnamigen <a href=\"#LP_113\" target=\"_blank\" rel=\"noopener\">Einsiedelei<\/a> f\u00fchrt, und an dem Tanz und dem Essen teilnehmen. Das ist auch die Gelegenheit, einige Zeit an dem <a href=\"#LP_98\" target=\"_blank\" rel=\"noopener\">wundersch\u00f6nen Strand<\/a> darunter zu verbringen!<\/p>\n<p>Es gibt viele andere Festlichkeiten, die das Leben <strong>in Lloret de Mar das ganze Jahr<\/strong> hindurch unterstreichen. Einige haben eine gro\u00dfe Anziehungskraft f\u00fcr die Kleinen und ihre Familien. Um mehr dar\u00fcber zu erfahren, lesen Sie bitte unseren Artikel <a href=\"#LP_144\" target=\"_blank\" rel=\"noopener\">\u201eAktivit\u00e4tenkalender f\u00fcr Kinder in Lloret de Mar\u201d<\/a>.<\/p>\n<p><strong>Genie\u00dfen Sie LLoret de Mar das ganze Jahr \u00fcber!<\/strong><\/p>\n<h4><a href=\"https:\/\/www.clubvillamar.de\/ferienhaus\/spanien\/costa-brava\/lloret-de-mar\" target=\"_blank\" rel=\"noopener\">Buchen Sie eine Unterkunft f\u00fcr Ihren n\u00e4chsten Urlaub.<\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Dieser Artikel \u00fcber die Feiertage und Feste in Lloret wird Ihnen erm\u00f6glichen, den Events in der Stadt beizuwohnen und die gem\u00fctliche Atmosph\u00e4re zu genie\u00dfen!<\/p>\n","protected":false},"author":3,"featured_media":20965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[6937,6939,6965],"tags":[292,1840,6861],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kalender der Feste und Feiertage in Lloret de Mar<\/title>\n<meta name=\"description\" content=\"Dieser Artikel \u00fcber die Feiertage und Feste in Lloret wird Ihnen erm\u00f6glichen, den Events in der Stadt beizuwohnen und die gem\u00fctliche Atmosph\u00e4re zu genie\u00dfen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kalender der Feste und Feiertage in Lloret de Mar\" \/>\n<meta property=\"og:description\" content=\"Dieser Artikel \u00fcber die Feiertage und Feste in Lloret wird Ihnen erm\u00f6glichen, den Events in der Stadt beizuwohnen und die gem\u00fctliche Atmosph\u00e4re zu genie\u00dfen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/\" \/>\n<meta property=\"og:site_name\" content=\"Club Villamar\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-23T23:38:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-19T10:56:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2018\/02\/feauterd-image-44-1024x576.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Club Villamar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Club Villamar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/\"},\"author\":{\"name\":\"Club Villamar\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62\"},\"headline\":\"Kalender der Feste und Feiertage in Lloret de Mar\",\"datePublished\":\"2018-02-23T23:38:30+00:00\",\"dateModified\":\"2018-03-19T10:56:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/\"},\"wordCount\":493,\"publisher\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#organization\"},\"keywords\":[\"lloret de mar\",\"Costa Brava\",\"spanien\"],\"articleSection\":[\"Spanien\",\"Costa Brava\",\"Lloret de Mar\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/\",\"url\":\"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/\",\"name\":\"Kalender der Feste und Feiertage in Lloret de Mar\",\"isPartOf\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#website\"},\"datePublished\":\"2018-02-23T23:38:30+00:00\",\"dateModified\":\"2018-03-19T10:56:01+00:00\",\"description\":\"Dieser Artikel \u00fcber die Feiertage und Feste in Lloret wird Ihnen erm\u00f6glichen, den Events in der Stadt beizuwohnen und die gem\u00fctliche Atmosph\u00e4re zu genie\u00dfen!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.clubvillamar.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kalender der Feste und Feiertage in Lloret de Mar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#website\",\"url\":\"https:\/\/www.clubvillamar.de\/blog\/\",\"name\":\"Club Villamar\",\"description\":\"Relax poolside at your private Spanish villa\",\"publisher\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.clubvillamar.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#organization\",\"name\":\"Club Villamar\",\"url\":\"https:\/\/www.clubvillamar.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg\",\"contentUrl\":\"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Club Villamar\"},\"image\":{\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62\",\"name\":\"Club Villamar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g\",\"caption\":\"Club Villamar\"},\"sameAs\":[\"https:\/\/www.clubvillamar.de\"],\"url\":\"https:\/\/www.clubvillamar.de\/blog\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kalender der Feste und Feiertage in Lloret de Mar","description":"Dieser Artikel \u00fcber die Feiertage und Feste in Lloret wird Ihnen erm\u00f6glichen, den Events in der Stadt beizuwohnen und die gem\u00fctliche Atmosph\u00e4re zu genie\u00dfen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/","og_locale":"de_DE","og_type":"article","og_title":"Kalender der Feste und Feiertage in Lloret de Mar","og_description":"Dieser Artikel \u00fcber die Feiertage und Feste in Lloret wird Ihnen erm\u00f6glichen, den Events in der Stadt beizuwohnen und die gem\u00fctliche Atmosph\u00e4re zu genie\u00dfen!","og_url":"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/","og_site_name":"Club Villamar","article_published_time":"2018-02-23T23:38:30+00:00","article_modified_time":"2018-03-19T10:56:01+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2018\/02\/feauterd-image-44-1024x576.jpg","type":"image\/jpeg"}],"author":"Club Villamar","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Club Villamar","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/#article","isPartOf":{"@id":"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/"},"author":{"name":"Club Villamar","@id":"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62"},"headline":"Kalender der Feste und Feiertage in Lloret de Mar","datePublished":"2018-02-23T23:38:30+00:00","dateModified":"2018-03-19T10:56:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/"},"wordCount":493,"publisher":{"@id":"https:\/\/www.clubvillamar.de\/blog\/#organization"},"keywords":["lloret de mar","Costa Brava","spanien"],"articleSection":["Spanien","Costa Brava","Lloret de Mar"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/","url":"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/","name":"Kalender der Feste und Feiertage in Lloret de Mar","isPartOf":{"@id":"https:\/\/www.clubvillamar.de\/blog\/#website"},"datePublished":"2018-02-23T23:38:30+00:00","dateModified":"2018-03-19T10:56:01+00:00","description":"Dieser Artikel \u00fcber die Feiertage und Feste in Lloret wird Ihnen erm\u00f6glichen, den Events in der Stadt beizuwohnen und die gem\u00fctliche Atmosph\u00e4re zu genie\u00dfen!","breadcrumb":{"@id":"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.clubvillamar.de\/blog\/spanien\/costa-brava\/lloret-de-mar\/kalender-der-feste-und-feiertage-in-lloret-de-mar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.clubvillamar.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Kalender der Feste und Feiertage in Lloret de Mar"}]},{"@type":"WebSite","@id":"https:\/\/www.clubvillamar.de\/blog\/#website","url":"https:\/\/www.clubvillamar.de\/blog\/","name":"Club Villamar","description":"Relax poolside at your private Spanish villa","publisher":{"@id":"https:\/\/www.clubvillamar.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clubvillamar.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.clubvillamar.de\/blog\/#organization","name":"Club Villamar","url":"https:\/\/www.clubvillamar.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg","contentUrl":"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2017\/10\/placeholder.jpg","width":1000,"height":1000,"caption":"Club Villamar"},"image":{"@id":"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/person\/603e65b5e4bf24837757a4b58cfe7b62","name":"Club Villamar","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.clubvillamar.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b7b837342835f6b0ba134ae80b58a01?s=96&d=mm&r=g","caption":"Club Villamar"},"sameAs":["https:\/\/www.clubvillamar.de"],"url":"https:\/\/www.clubvillamar.de\/blog\/author\/marketing\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.clubvillamar.de\/blog\/wp-content\/uploads\/2018\/02\/feauterd-image-44.jpg","jetpack_shortlink":"https:\/\/wp.me\/p9D9kG-5eE","_links":{"self":[{"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/posts\/20128"}],"collection":[{"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/comments?post=20128"}],"version-history":[{"count":3,"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/posts\/20128\/revisions"}],"predecessor-version":[{"id":21404,"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/posts\/20128\/revisions\/21404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/media\/20965"}],"wp:attachment":[{"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/media?parent=20128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/categories?post=20128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubvillamar.de\/blog\/wp-json\/wp\/v2\/tags?post=20128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}